{"id":255,"count":37,"description":"","link":"https:\/\/longaliisu.ee\/de\/kategorie\/onlineshop\/frauen-ponchos\/","name":"Frauen Ponchos","slug":"frauen-ponchos","taxonomy":"product_cat","parent":211,"meta":[],"menu_order":5,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Frauen Ponchos Archives - L\u00f5nga Liisu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longaliisu.ee\/de\/kategorie\/onlineshop\/frauen-ponchos\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frauen Ponchos Archives - L\u00f5nga Liisu\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longaliisu.ee\/de\/kategorie\/onlineshop\/frauen-ponchos\/\" \/>\n<meta property=\"og:site_name\" content=\"L\u00f5nga Liisu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/kategorie\\\/onlineshop\\\/frauen-ponchos\\\/\",\"url\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/kategorie\\\/onlineshop\\\/frauen-ponchos\\\/\",\"name\":\"Frauen Ponchos Archives - L\u00f5nga Liisu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/kategorie\\\/onlineshop\\\/frauen-ponchos\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/kategorie\\\/onlineshop\\\/frauen-ponchos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Onlineshop\",\"item\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/kategorie\\\/onlineshop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Frauen Ponchos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/#website\",\"url\":\"https:\\\/\\\/longaliisu.ee\\\/\",\"name\":\"L\u00f5nga Liisu\",\"description\":\"L\u00f5nga Liisu k\u00e4sit\u00f6\u00f6 ja kudumid\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/longaliisu.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frauen Ponchos Archives - L\u00f5nga Liisu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longaliisu.ee\/de\/kategorie\/onlineshop\/frauen-ponchos\/","og_locale":"de_DE","og_type":"article","og_title":"Frauen Ponchos Archives - L\u00f5nga Liisu","og_url":"https:\/\/longaliisu.ee\/de\/kategorie\/onlineshop\/frauen-ponchos\/","og_site_name":"L\u00f5nga Liisu","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/longaliisu.ee\/de\/kategorie\/onlineshop\/frauen-ponchos\/","url":"https:\/\/longaliisu.ee\/de\/kategorie\/onlineshop\/frauen-ponchos\/","name":"Frauen Ponchos Archives - L\u00f5nga Liisu","isPartOf":{"@id":"https:\/\/longaliisu.ee\/#website"},"breadcrumb":{"@id":"https:\/\/longaliisu.ee\/de\/kategorie\/onlineshop\/frauen-ponchos\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/longaliisu.ee\/de\/kategorie\/onlineshop\/frauen-ponchos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longaliisu.ee\/de\/"},{"@type":"ListItem","position":2,"name":"Onlineshop","item":"https:\/\/longaliisu.ee\/de\/kategorie\/onlineshop\/"},{"@type":"ListItem","position":3,"name":"Frauen Ponchos"}]},{"@type":"WebSite","@id":"https:\/\/longaliisu.ee\/#website","url":"https:\/\/longaliisu.ee\/","name":"L\u00f5nga Liisu","description":"L\u00f5nga Liisu k\u00e4sit\u00f6\u00f6 ja kudumid","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longaliisu.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/product_cat\/255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/product_cat\/211"}],"wp:post_type":[{"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/product?product_cat=255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}