{"id":5025,"date":"2017-03-22T18:10:56","date_gmt":"2017-03-22T16:10:56","guid":{"rendered":"https:\/\/longaliisu.ee\/toode\/blauer-poncho-mit-kaputze\/"},"modified":"2023-08-20T00:06:36","modified_gmt":"2023-08-19T21:06:36","slug":"blauer-poncho-mit-kaputze","status":"publish","type":"product","link":"https:\/\/longaliisu.ee\/de\/produkt\/blauer-poncho-mit-kaputze\/","title":{"rendered":"Blauer Poncho mit Kaputze"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Poncho in blauen T\u00f6nen und mit einem traditionellem Muster.<\/p>\n<p>Lieferzeit bis 3 Wochen.<\/p>\n","protected":false},"featured_media":5019,"template":"","meta":[],"product_brand":[],"product_cat":[255],"product_tag":[217,222,218],"class_list":{"0":"post-5025","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-frauen-ponchos","7":"product_tag-blau","8":"product_tag-kaputze","9":"product_tag-traditionell","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Blauer Poncho mit Kaputze - L\u00f5nga Liisu<\/title>\n<meta name=\"description\" content=\"Poncho in blauen T\u00f6nen und mit einem traditionellem Muster.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longaliisu.ee\/de\/produkt\/blauer-poncho-mit-kaputze\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blauer Poncho mit Kaputze - L\u00f5nga Liisu\" \/>\n<meta property=\"og:description\" content=\"Poncho in blauen T\u00f6nen und mit einem traditionellem Muster.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longaliisu.ee\/de\/produkt\/blauer-poncho-mit-kaputze\/\" \/>\n<meta property=\"og:site_name\" content=\"L\u00f5nga Liisu\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-19T21:06:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/longaliisu.ee\/wp-content\/uploads\/2017\/03\/DSC_0083.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/produkt\\\/blauer-poncho-mit-kaputze\\\/\",\"url\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/produkt\\\/blauer-poncho-mit-kaputze\\\/\",\"name\":\"Blauer Poncho mit Kaputze - L\u00f5nga Liisu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/produkt\\\/blauer-poncho-mit-kaputze\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/produkt\\\/blauer-poncho-mit-kaputze\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/longaliisu.ee\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/DSC_0083.jpg\",\"datePublished\":\"2017-03-22T16:10:56+00:00\",\"dateModified\":\"2023-08-19T21:06:36+00:00\",\"description\":\"Poncho in blauen T\u00f6nen und mit einem traditionellem Muster.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/produkt\\\/blauer-poncho-mit-kaputze\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/longaliisu.ee\\\/de\\\/produkt\\\/blauer-poncho-mit-kaputze\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/produkt\\\/blauer-poncho-mit-kaputze\\\/#primaryimage\",\"url\":\"https:\\\/\\\/longaliisu.ee\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/DSC_0083.jpg\",\"contentUrl\":\"https:\\\/\\\/longaliisu.ee\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/DSC_0083.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/produkt\\\/blauer-poncho-mit-kaputze\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E-store\",\"item\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/e-store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Blauer Poncho mit Kaputze\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/#website\",\"url\":\"https:\\\/\\\/longaliisu.ee\\\/\",\"name\":\"L\u00f5nga Liisu\",\"description\":\"L\u00f5nga Liisu k\u00e4sit\u00f6\u00f6 ja kudumid\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/longaliisu.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blauer Poncho mit Kaputze - L\u00f5nga Liisu","description":"Poncho in blauen T\u00f6nen und mit einem traditionellem Muster.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longaliisu.ee\/de\/produkt\/blauer-poncho-mit-kaputze\/","og_locale":"de_DE","og_type":"article","og_title":"Blauer Poncho mit Kaputze - L\u00f5nga Liisu","og_description":"Poncho in blauen T\u00f6nen und mit einem traditionellem Muster.","og_url":"https:\/\/longaliisu.ee\/de\/produkt\/blauer-poncho-mit-kaputze\/","og_site_name":"L\u00f5nga Liisu","article_modified_time":"2023-08-19T21:06:36+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/longaliisu.ee\/wp-content\/uploads\/2017\/03\/DSC_0083.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longaliisu.ee\/de\/produkt\/blauer-poncho-mit-kaputze\/","url":"https:\/\/longaliisu.ee\/de\/produkt\/blauer-poncho-mit-kaputze\/","name":"Blauer Poncho mit Kaputze - L\u00f5nga Liisu","isPartOf":{"@id":"https:\/\/longaliisu.ee\/#website"},"primaryImageOfPage":{"@id":"https:\/\/longaliisu.ee\/de\/produkt\/blauer-poncho-mit-kaputze\/#primaryimage"},"image":{"@id":"https:\/\/longaliisu.ee\/de\/produkt\/blauer-poncho-mit-kaputze\/#primaryimage"},"thumbnailUrl":"https:\/\/longaliisu.ee\/wp-content\/uploads\/2017\/03\/DSC_0083.jpg","datePublished":"2017-03-22T16:10:56+00:00","dateModified":"2023-08-19T21:06:36+00:00","description":"Poncho in blauen T\u00f6nen und mit einem traditionellem Muster.","breadcrumb":{"@id":"https:\/\/longaliisu.ee\/de\/produkt\/blauer-poncho-mit-kaputze\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longaliisu.ee\/de\/produkt\/blauer-poncho-mit-kaputze\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/longaliisu.ee\/de\/produkt\/blauer-poncho-mit-kaputze\/#primaryimage","url":"https:\/\/longaliisu.ee\/wp-content\/uploads\/2017\/03\/DSC_0083.jpg","contentUrl":"https:\/\/longaliisu.ee\/wp-content\/uploads\/2017\/03\/DSC_0083.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/longaliisu.ee\/de\/produkt\/blauer-poncho-mit-kaputze\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longaliisu.ee\/de\/"},{"@type":"ListItem","position":2,"name":"E-store","item":"https:\/\/longaliisu.ee\/de\/e-store\/"},{"@type":"ListItem","position":3,"name":"Blauer Poncho mit Kaputze"}]},{"@type":"WebSite","@id":"https:\/\/longaliisu.ee\/#website","url":"https:\/\/longaliisu.ee\/","name":"L\u00f5nga Liisu","description":"L\u00f5nga Liisu k\u00e4sit\u00f6\u00f6 ja kudumid","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longaliisu.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/product\/5025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/media\/5019"}],"wp:attachment":[{"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/media?parent=5025"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/product_brand?post=5025"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/product_cat?post=5025"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/product_tag?post=5025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}