{"id":4541,"date":"2017-04-15T15:54:02","date_gmt":"2017-04-15T12:54:02","guid":{"rendered":"https:\/\/longaliisu.ee\/toode\/fur-einen-frohlichen-menschen-mit-guter-laune\/"},"modified":"2020-10-27T17:19:31","modified_gmt":"2020-10-27T15:19:31","slug":"fur-einen-frohlichen-menschen-mit-guter-laune","status":"publish","type":"product","link":"https:\/\/longaliisu.ee\/de\/produkt\/fur-einen-frohlichen-menschen-mit-guter-laune\/","title":{"rendered":"F\u00fcr einen fr\u00f6hlichen Menschen mit guter Laune"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Set mit hellgrau-schwarzem traditionellem Muster mit Ornamenten.<\/p>\n<p>Schal hat eine Einheitsgr\u00f6\u00dfe (breite 15-16 cm, l\u00e4nge 150 cm).<\/p>\n<p>Lieferzeit bis 3 Wochen.<\/p>\n","protected":false},"featured_media":4550,"template":"","meta":[],"product_brand":[],"product_cat":[212],"product_tag":[216,214,218],"class_list":{"0":"post-4541","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-sets","7":"product_tag-ornament-de","8":"product_tag-schwarz","9":"product_tag-traditionell","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00fcr einen fr\u00f6hlichen Menschen mit guter Laune - L\u00f5nga Liisu<\/title>\n<meta name=\"description\" content=\"Set mit hellgrau-schwarzem traditionellem Muster mit Ornamenten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/longaliisu.ee\/de\/produkt\/fur-einen-frohlichen-menschen-mit-guter-laune\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F\u00fcr einen fr\u00f6hlichen Menschen mit guter Laune - L\u00f5nga Liisu\" \/>\n<meta property=\"og:description\" content=\"Set mit hellgrau-schwarzem traditionellem Muster mit Ornamenten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/longaliisu.ee\/de\/produkt\/fur-einen-frohlichen-menschen-mit-guter-laune\/\" \/>\n<meta property=\"og:site_name\" content=\"L\u00f5nga Liisu\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-27T15:19:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/longaliisu.ee\/wp-content\/uploads\/2017\/04\/DSC_0662.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/produkt\\\/fur-einen-frohlichen-menschen-mit-guter-laune\\\/\",\"url\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/produkt\\\/fur-einen-frohlichen-menschen-mit-guter-laune\\\/\",\"name\":\"F\u00fcr einen fr\u00f6hlichen Menschen mit guter Laune - L\u00f5nga Liisu\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/produkt\\\/fur-einen-frohlichen-menschen-mit-guter-laune\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/produkt\\\/fur-einen-frohlichen-menschen-mit-guter-laune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/longaliisu.ee\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/DSC_0662.jpg\",\"datePublished\":\"2017-04-15T12:54:02+00:00\",\"dateModified\":\"2020-10-27T15:19:31+00:00\",\"description\":\"Set mit hellgrau-schwarzem traditionellem Muster mit Ornamenten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/produkt\\\/fur-einen-frohlichen-menschen-mit-guter-laune\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/longaliisu.ee\\\/de\\\/produkt\\\/fur-einen-frohlichen-menschen-mit-guter-laune\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/produkt\\\/fur-einen-frohlichen-menschen-mit-guter-laune\\\/#primaryimage\",\"url\":\"https:\\\/\\\/longaliisu.ee\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/DSC_0662.jpg\",\"contentUrl\":\"https:\\\/\\\/longaliisu.ee\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/DSC_0662.jpg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/produkt\\\/fur-einen-frohlichen-menschen-mit-guter-laune\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E-store\",\"item\":\"https:\\\/\\\/longaliisu.ee\\\/de\\\/e-store\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"F\u00fcr einen fr\u00f6hlichen Menschen mit guter Laune\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/longaliisu.ee\\\/#website\",\"url\":\"https:\\\/\\\/longaliisu.ee\\\/\",\"name\":\"L\u00f5nga Liisu\",\"description\":\"L\u00f5nga Liisu k\u00e4sit\u00f6\u00f6 ja kudumid\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/longaliisu.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00fcr einen fr\u00f6hlichen Menschen mit guter Laune - L\u00f5nga Liisu","description":"Set mit hellgrau-schwarzem traditionellem Muster mit Ornamenten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/longaliisu.ee\/de\/produkt\/fur-einen-frohlichen-menschen-mit-guter-laune\/","og_locale":"de_DE","og_type":"article","og_title":"F\u00fcr einen fr\u00f6hlichen Menschen mit guter Laune - L\u00f5nga Liisu","og_description":"Set mit hellgrau-schwarzem traditionellem Muster mit Ornamenten.","og_url":"https:\/\/longaliisu.ee\/de\/produkt\/fur-einen-frohlichen-menschen-mit-guter-laune\/","og_site_name":"L\u00f5nga Liisu","article_modified_time":"2020-10-27T15:19:31+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/longaliisu.ee\/wp-content\/uploads\/2017\/04\/DSC_0662.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/longaliisu.ee\/de\/produkt\/fur-einen-frohlichen-menschen-mit-guter-laune\/","url":"https:\/\/longaliisu.ee\/de\/produkt\/fur-einen-frohlichen-menschen-mit-guter-laune\/","name":"F\u00fcr einen fr\u00f6hlichen Menschen mit guter Laune - L\u00f5nga Liisu","isPartOf":{"@id":"https:\/\/longaliisu.ee\/#website"},"primaryImageOfPage":{"@id":"https:\/\/longaliisu.ee\/de\/produkt\/fur-einen-frohlichen-menschen-mit-guter-laune\/#primaryimage"},"image":{"@id":"https:\/\/longaliisu.ee\/de\/produkt\/fur-einen-frohlichen-menschen-mit-guter-laune\/#primaryimage"},"thumbnailUrl":"https:\/\/longaliisu.ee\/wp-content\/uploads\/2017\/04\/DSC_0662.jpg","datePublished":"2017-04-15T12:54:02+00:00","dateModified":"2020-10-27T15:19:31+00:00","description":"Set mit hellgrau-schwarzem traditionellem Muster mit Ornamenten.","breadcrumb":{"@id":"https:\/\/longaliisu.ee\/de\/produkt\/fur-einen-frohlichen-menschen-mit-guter-laune\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/longaliisu.ee\/de\/produkt\/fur-einen-frohlichen-menschen-mit-guter-laune\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/longaliisu.ee\/de\/produkt\/fur-einen-frohlichen-menschen-mit-guter-laune\/#primaryimage","url":"https:\/\/longaliisu.ee\/wp-content\/uploads\/2017\/04\/DSC_0662.jpg","contentUrl":"https:\/\/longaliisu.ee\/wp-content\/uploads\/2017\/04\/DSC_0662.jpg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/longaliisu.ee\/de\/produkt\/fur-einen-frohlichen-menschen-mit-guter-laune\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/longaliisu.ee\/de\/"},{"@type":"ListItem","position":2,"name":"E-store","item":"https:\/\/longaliisu.ee\/de\/e-store\/"},{"@type":"ListItem","position":3,"name":"F\u00fcr einen fr\u00f6hlichen Menschen mit guter Laune"}]},{"@type":"WebSite","@id":"https:\/\/longaliisu.ee\/#website","url":"https:\/\/longaliisu.ee\/","name":"L\u00f5nga Liisu","description":"L\u00f5nga Liisu k\u00e4sit\u00f6\u00f6 ja kudumid","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/longaliisu.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/product\/4541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/media\/4550"}],"wp:attachment":[{"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/media?parent=4541"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/product_brand?post=4541"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/product_cat?post=4541"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/longaliisu.ee\/de\/wp-json\/wp\/v2\/product_tag?post=4541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}